{"id":29,"count":0,"description":"Stanley est un fabricant de sachets \u00e0 quadruple soudure qui se consacre \u00e0 la fourniture de sachets d'emballage flexibles personnalis\u00e9s, durables et visuellement attrayants, \u00e0 des clients du monde entier. La structure du sac \u00e0 quadruple soudure am\u00e9liore la verticalit\u00e9 et la pr\u00e9sentation en rayon, et convient \u00e0 une vari\u00e9t\u00e9 de produits tels que le caf\u00e9, les snacks, les aliments pour animaux de compagnie, les c\u00e9r\u00e9ales, etc.","link":"https:\/\/www.stanleypackage.com\/fr\/product-category\/quad-seal-bag-manufacturer\/","name":"Pochette Quad Seal","slug":"quad-seal-bag-manufacturer","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.stanleypackage.com\/fr\/wp-json\/wp\/v2\/product_cat\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stanleypackage.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.stanleypackage.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.stanleypackage.com\/fr\/wp-json\/wp\/v2\/product?product_cat=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}